{"id":24114,"date":"2023-09-03T10:43:42","date_gmt":"2023-09-03T04:43:42","guid":{"rendered":"https:\/\/www.askbd.org\/ask\/?p=24114"},"modified":"2023-10-04T13:50:24","modified_gmt":"2023-10-04T07:50:24","slug":"deaths-in-jail-custody-jan-aug-2023","status":"publish","type":"post","link":"https:\/\/www.askbd.org\/ask\/2023\/09\/03\/deaths-in-jail-custody-jan-aug-2023\/","title":{"rendered":"Deaths in Jail Custody (Jan-Aug 2023)"},"content":{"rendered":"<p><a href=\"https:\/\/www.askbd.org\/ask\/wp-content\/uploads\/2023\/10\/Death-in-Jail-Custody-Divisionwise-January-August-2023-min.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.askbd.org\/ask\/wp-content\/uploads\/2023\/10\/Death-in-Jail-Custody-Divisionwise-January-August-2023-min.jpg\" alt=\"\" width=\"800\" height=\"380\" class=\"aligncenter size-full wp-image-24115\" srcset=\"https:\/\/www.askbd.org\/ask\/wp-content\/uploads\/2023\/10\/Death-in-Jail-Custody-Divisionwise-January-August-2023-min.jpg 800w, https:\/\/www.askbd.org\/ask\/wp-content\/uploads\/2023\/10\/Death-in-Jail-Custody-Divisionwise-January-August-2023-min-768x365.jpg 768w, https:\/\/www.askbd.org\/ask\/wp-content\/uploads\/2023\/10\/Death-in-Jail-Custody-Divisionwise-January-August-2023-min-600x285.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>Can\u2019t see? <a href=\"https:\/\/drive.google.com\/file\/d\/1AwHcqlBdRFVFBFfrGH5xiCZG4hgp7tnF\/preview\">Please click here to open PDF file.<\/a><br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/1AwHcqlBdRFVFBFfrGH5xiCZG4hgp7tnF\/preview\" width=\"100%\" height=\"480\" allow=\"autoplay\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Can\u2019t see? Please click here to open PDF file.<\/p>\n","protected":false},"author":1,"featured_media":22018,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,23],"tags":[],"class_list":["post-24114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-death-in-jail-custody","category-hr-monitoring"],"_links":{"self":[{"href":"https:\/\/www.askbd.org\/ask\/wp-json\/wp\/v2\/posts\/24114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.askbd.org\/ask\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.askbd.org\/ask\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.askbd.org\/ask\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.askbd.org\/ask\/wp-json\/wp\/v2\/comments?post=24114"}],"version-history":[{"count":1,"href":"https:\/\/www.askbd.org\/ask\/wp-json\/wp\/v2\/posts\/24114\/revisions"}],"predecessor-version":[{"id":24116,"href":"https:\/\/www.askbd.org\/ask\/wp-json\/wp\/v2\/posts\/24114\/revisions\/24116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.askbd.org\/ask\/wp-json\/wp\/v2\/media\/22018"}],"wp:attachment":[{"href":"https:\/\/www.askbd.org\/ask\/wp-json\/wp\/v2\/media?parent=24114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.askbd.org\/ask\/wp-json\/wp\/v2\/categories?post=24114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.askbd.org\/ask\/wp-json\/wp\/v2\/tags?post=24114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}